{"id":3026,"date":"2016-06-20T00:00:00","date_gmt":"2016-06-20T04:00:00","guid":{"rendered":"http:\/\/184.107.41.70\/~ctffce\/perspectives_cpt\/vivre-en-francais-en-terre-inuite\/"},"modified":"2016-06-20T00:00:00","modified_gmt":"2016-06-20T04:00:00","slug":"vivre-en-francais-en-terre-inuite","status":"publish","type":"perspectives_cpt","link":"https:\/\/www.ctf-fce.ca\/fr\/journal-education-publique\/vivre-en-francais-en-terre-inuite\/","title":{"rendered":"Vivre en fran\u00e7ais en terre inuite"},"content":{"rendered":"<p><a href=\"http:\/\/trois-soleils.ca\/troissol\/\">L\u2019\u00e9cole des Trois-Soleils<\/a> a la particularit\u00e9 d\u2019\u00eatre l\u2019\u00e9cole de langue fran\u00e7aise la plus nordique au monde. Trois-Soleils en raison du ph\u00e9nom\u00e8ne de parh\u00e9lie qui a lieu en hiver, mais aussi pour rappeler la pr\u00e9sence de trois langues bien pr\u00e9sentes dans la communaut\u00e9&nbsp;: l\u2019inuktitut, le fran\u00e7ais et l\u2019anglais. Elle accueille les \u00e9l\u00e8ves francophones d\u2019Iqaluit et offre comme d\u00e9cor la baie Frobisher. <\/p>\n<p>Si la raison de cette excursion en territoire inuit \u00e9tait li\u00e9e au tournage de vid\u00e9os p\u00e9dagogiques, c\u2019\u00e9tait aussi l\u2019occasion r\u00eav\u00e9e pour explorer la r\u00e9alit\u00e9 quotidienne de ces francophones qui habitent au pays des Inuits.<\/p>\n<p>Iqaluit est la capitale du Nunavut. Environ 60&nbsp;% de cette population de plus de 7&nbsp;000 habitants est inuite et 1,3&nbsp;% est francophone. Bien que la pr\u00e9sence francophone date de plusieurs centaines d\u2019ann\u00e9es, ce n\u2019est que depuis une trentaine d\u2019ann\u00e9es qu\u2019elle s\u2019accro\u00eet de fa\u00e7on plus marquante.<\/p>\n<p>Quels liens existent entre les Inuits et les francophones? Les francophones rencontr\u00e9s l\u00e0-bas s\u2019entendent pour dire qu\u2019ils sont fond\u00e9s sur le respect, mais que ces liens restent \u00e0 \u00eatre d\u00e9velopp\u00e9s. En effet, bien qu\u2019ils soient majoritaires en nombre, les Inuits vivent des d\u00e9fis qui s\u2019apparentent \u00e0 ceux de la minorit\u00e9 francophone&nbsp;: la perte de locuteurs vers l\u2019anglais, le manque de ressources dans leur langue, la transmission de la culture en sont des exemples. \u00ab&nbsp;On sent qu\u2019on aurait une contribution \u00e0 faire \u00e0 l\u2019\u00e9panouissement de la communaut\u00e9 inuite, mais les ponts restent \u00e0 \u00eatre cr\u00e9\u00e9s&nbsp;\u00bb, reconna\u00eet un francophone engag\u00e9 du milieu.<\/p>\n<p>Vivre en fran\u00e7ais n\u2019est pas chose facile dans un endroit aussi isol\u00e9. Dans les ann\u00e9es&nbsp;70, plusieurs francophones du Qu\u00e9bec ont \u00e9t\u00e9 recrut\u00e9s par Bell pour b\u00e2tir les infrastructures n\u00e9cessaires \u00e0 l\u2019essor de la ville. C\u2019est la <em>Soir\u00e9e du hockey<\/em> qui manquait particuli\u00e8rement \u00e0 ce groupe de jeunes qu\u00e9b\u00e9cois et qui a men\u00e9, en 1981, \u00e0 la cr\u00e9ation de <a href=\"http:\/\/www.afnunavut.ca\/\">l\u2019Association des francophones du Nunavut<\/a>. Le premier objectif du rassemblement \u00e9tait, en effet, la diffusion de la c\u00e9l\u00e8bre \u00e9mission. L\u2019Association a par ailleurs \u00e9t\u00e9 responsable du signal t\u00e9l\u00e9visuel jusqu\u2019au tournant du si\u00e8cle, alors que les droits ont \u00e9t\u00e9 remis au c\u00e2blodistributeur local. Les d\u00e9marches pour la cr\u00e9ation d\u2019une \u00e9cole de langue fran\u00e7aise n\u2019ont pas \u00e9t\u00e9 faciles non plus. \u00ab&nbsp;Ce sont ces exp\u00e9riences de revendication qui font qu\u2019on comprend bien la situation de la communaut\u00e9 inuite&nbsp;\u00bb, pr\u00e9cise un artisan de la francophonie du Nunavut.<\/p>\n<div style=\"float: right; width: 50%; min-width:400px; margin-left:10px; margin-top:10px; margin-bottom:0px;\">\n<p style=\"text-align:center\"><img decoding=\"async\" style=\"max-width:100%;height:auto;\" src=\"http:\/\/perspectives.ctf-fce.ca\/Documents\/Articles\/Issue22\/Graphics\/article5b.jpg\" alt=\"\" \/><\/p>\n<p style=\"font-size:0.96em;text-align:center;color:#888;\">Vue de la fen\u00eatre d\u2019une salle de classe de<br \/>\nl\u2019\u00e9cole des <span style=\"white-space:nowrap;\">Trois-Soleils.<\/span><\/p>\n<\/div>\n<p>Signe d\u2019int\u00e9gration \u00e0 son milieu, l&rsquo;\u00e9cole de langue fran\u00e7aise int\u00e8gre les valeurs inuites \u00e0 l\u2019enseignement. Bien en \u00e9vidence dans les classes, on rappelle aux \u00e9l\u00e8ves l\u2019importance du respect de l\u2019autre, de l\u2019ouverture d\u2019esprit, de l\u2019engagement communautaire, de la prise de d\u00e9cision par consensus, des strat\u00e9gies de d\u00e9veloppement des comp\u00e9tences, de la concertation des efforts, de la recherche de solutions et du respect de l\u2019environnement. <\/p>\n<p>Quelques francophones ont appris l\u2019inuktitut ou se d\u00e9brouillent assez bien pour maintenir une conversation. \u00ab&nbsp;Quand un \u00e9tranger apprend quelques mots de fran\u00e7ais, on l\u2019appr\u00e9cie toujours. C\u2019est un peu normal pour nous d\u2019apprendre les rudiments de la langue des Inuits. C\u2019est une fa\u00e7on de d\u00e9montrer du respect.&nbsp;\u00bb C\u2019est un petit geste qui prend son sens quand on sait que le maintien du nombre de locuteurs inuits pr\u00e9sente des d\u00e9fis. La langue est de moins en moins parl\u00e9e au foyer, lieu privil\u00e9gi\u00e9 pour sa transmission. <\/p>\n<p>Certains francophones ont aussi trouv\u00e9 l\u2019amour dans la communaut\u00e9 inuite. Une rencontre avec un p\u00e8re francophone et son fils issu du mariage avec une Inuite am\u00e8ne une autre perspective \u00e0 la question des liens entre les deux communaut\u00e9s. Le p\u00e8re a appris l\u2019inuktitut, surtout avec les <em>elders<\/em>, \u00ab&nbsp;des p\u00e9dagogues dans l\u2019\u00e2me&nbsp;\u00bb, confie-t-il. \u00ab&nbsp;C\u2019\u00e9tait important pour moi de cr\u00e9er des liens avec la famille.&nbsp;\u00bb Le fils est un produit de l\u2019\u00e9cole de langue fran\u00e7aise et parle couramment l\u2019anglais et le fran\u00e7ais. Comme d\u2019autres jeunes rencontr\u00e9s lors de ce bref s\u00e9jour, la question identitaire n\u2019est pas au c\u0153ur des interactions entre eux. Tous ont des amis inuits, francophones et anglophones. La langue utilis\u00e9e entre eux varie selon le contexte.<\/p>\n<p>Le mot de la fin revient \u00e0 ce p\u00e8re qui met toute sa confiance dans les jeunes. \u00ab&nbsp;Ce sont eux qui feront tomber les barri\u00e8res et qui donneront un nouvel \u00e9lan \u00e0 la francophonie du Nunavut.&nbsp;\u00bb <\/p>\n<p>Comme lui, faisons le v\u0153u que la nouvelle g\u00e9n\u00e9ration fasse briller les trois soleils encore longtemps!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>D\u00e9couvrez comment une \u00e9cole de langue fran\u00e7aise au<br \/>\nc\u0153ur d\u2019Iqaluit aide \u00e0 pr\u00e9server la vitalit\u00e9 du fran\u00e7ais dans cette communaut\u00e9<br \/>\n\u00e9loign\u00e9e du Nord.<\/p>\n","protected":false},"author":1,"featured_media":1235,"menu_order":0,"comment_status":"closed","ping_status":"open","template":"","format":"standard","meta":{"_acf_changed":false,"advgb_blocks_editor_width":"","advgb_blocks_columns_visual_guide":"","footnotes":""},"categories_perspectives_cpt":[504,500],"authors_perspectives_cpt":[391],"class_list":["post-3026","perspectives_cpt","type-perspectives_cpt","status-publish","format-standard","has-post-thumbnail","hentry","categories_perspectives_cpt-education-autochtone","categories_perspectives_cpt-francophonie-fr","authors_perspectives_cpt-ronald-boudreau-fr"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Vivre en fran\u00e7ais en terre inuite<\/title>\n<meta name=\"description\" content=\"D\u00e9couvrez comment une \u00e9cole de langue fran\u00e7aise au c\u0153ur d\u2019Iqaluit aide \u00e0 pr\u00e9server la vitalit\u00e9 du fran\u00e7ais dans cette communaut\u00e9 \u00e9loign\u00e9e du Nord.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ctf-fce.ca\/fr\/journal-education-publique\/vivre-en-francais-en-terre-inuite\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Vivre en fran\u00e7ais en terre inuite\" \/>\n<meta property=\"og:description\" content=\"D\u00e9couvrez comment une \u00e9cole de langue fran\u00e7aise au c\u0153ur d\u2019Iqaluit aide \u00e0 pr\u00e9server la vitalit\u00e9 du fran\u00e7ais dans cette communaut\u00e9 \u00e9loign\u00e9e du Nord.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ctf-fce.ca\/fr\/journal-education-publique\/vivre-en-francais-en-terre-inuite\/\" \/>\n<meta property=\"og:site_name\" content=\"CTF-FCE\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/CTF.FCE\/\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ctf-fce.ca\/wp-content\/uploads\/2020\/02\/article5.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Vivre en fran\u00e7ais en terre inuite\" \/>\n<meta name=\"twitter:description\" content=\"D\u00e9couvrez comment une \u00e9cole de langue fran\u00e7aise au c\u0153ur d\u2019Iqaluit aide \u00e0 pr\u00e9server la vitalit\u00e9 du fran\u00e7ais dans cette communaut\u00e9 \u00e9loign\u00e9e du Nord.\" \/>\n<meta name=\"twitter:site\" content=\"@CTFFCE\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.ctf-fce.ca\\\/fr\\\/journal-education-publique\\\/vivre-en-francais-en-terre-inuite\\\/\",\"url\":\"https:\\\/\\\/www.ctf-fce.ca\\\/fr\\\/journal-education-publique\\\/vivre-en-francais-en-terre-inuite\\\/\",\"name\":\"Vivre en fran\u00e7ais en terre inuite\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ctf-fce.ca\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.ctf-fce.ca\\\/fr\\\/journal-education-publique\\\/vivre-en-francais-en-terre-inuite\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ctf-fce.ca\\\/fr\\\/journal-education-publique\\\/vivre-en-francais-en-terre-inuite\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.ctf-fce.ca\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/article5.jpg\",\"datePublished\":\"2016-06-20T04:00:00+00:00\",\"description\":\"D\u00e9couvrez comment une \u00e9cole de langue fran\u00e7aise au c\u0153ur d\u2019Iqaluit aide \u00e0 pr\u00e9server la vitalit\u00e9 du fran\u00e7ais dans cette communaut\u00e9 \u00e9loign\u00e9e du Nord.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.ctf-fce.ca\\\/fr\\\/journal-education-publique\\\/vivre-en-francais-en-terre-inuite\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.ctf-fce.ca\\\/fr\\\/journal-education-publique\\\/vivre-en-francais-en-terre-inuite\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.ctf-fce.ca\\\/fr\\\/journal-education-publique\\\/vivre-en-francais-en-terre-inuite\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.ctf-fce.ca\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/article5.jpg\",\"contentUrl\":\"https:\\\/\\\/www.ctf-fce.ca\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/article5.jpg\",\"width\":800,\"height\":500,\"caption\":\"Les participantes et participants du Projet outre-mer de&nbsp;1967 s\u2019appr\u00eatant \u00e0 prendre l\u2019avion vers leur pays d\u2019affectation.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.ctf-fce.ca\\\/fr\\\/journal-education-publique\\\/vivre-en-francais-en-terre-inuite\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.ctf-fce.ca\\\/fr\\\/home\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Journal de l\u2019\u00e9ducation publique\",\"item\":\"https:\\\/\\\/www.ctf-fce.ca\\\/fr\\\/journal-education-publique\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Vivre en fran\u00e7ais en terre inuite\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.ctf-fce.ca\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.ctf-fce.ca\\\/fr\\\/\",\"name\":\"CTF-FCE\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.ctf-fce.ca\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.ctf-fce.ca\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.ctf-fce.ca\\\/fr\\\/#organization\",\"name\":\"CTF-FCE\",\"url\":\"https:\\\/\\\/www.ctf-fce.ca\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.ctf-fce.ca\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.ctf-fce.ca\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/ctf-fce-logo@2x.png\",\"contentUrl\":\"https:\\\/\\\/www.ctf-fce.ca\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/ctf-fce-logo@2x.png\",\"width\":485,\"height\":146,\"caption\":\"CTF-FCE\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ctf-fce.ca\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/CTF.FCE\\\/\",\"https:\\\/\\\/x.com\\\/CTFFCE\",\"https:\\\/\\\/www.instagram.com\\\/ctffce\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/canadian-teachers'\u200b-federation---f\u00e9d.-canadienne-des-enseignantes-et-des-enseignants\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/canadianteachers\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Vivre en fran\u00e7ais en terre inuite","description":"D\u00e9couvrez comment une \u00e9cole de langue fran\u00e7aise au c\u0153ur d\u2019Iqaluit aide \u00e0 pr\u00e9server la vitalit\u00e9 du fran\u00e7ais dans cette communaut\u00e9 \u00e9loign\u00e9e du Nord.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ctf-fce.ca\/fr\/journal-education-publique\/vivre-en-francais-en-terre-inuite\/","og_locale":"fr_FR","og_type":"article","og_title":"Vivre en fran\u00e7ais en terre inuite","og_description":"D\u00e9couvrez comment une \u00e9cole de langue fran\u00e7aise au c\u0153ur d\u2019Iqaluit aide \u00e0 pr\u00e9server la vitalit\u00e9 du fran\u00e7ais dans cette communaut\u00e9 \u00e9loign\u00e9e du Nord.","og_url":"https:\/\/www.ctf-fce.ca\/fr\/journal-education-publique\/vivre-en-francais-en-terre-inuite\/","og_site_name":"CTF-FCE","article_publisher":"https:\/\/www.facebook.com\/CTF.FCE\/","og_image":[{"width":800,"height":500,"url":"https:\/\/www.ctf-fce.ca\/wp-content\/uploads\/2020\/02\/article5.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_title":"Vivre en fran\u00e7ais en terre inuite","twitter_description":"D\u00e9couvrez comment une \u00e9cole de langue fran\u00e7aise au c\u0153ur d\u2019Iqaluit aide \u00e0 pr\u00e9server la vitalit\u00e9 du fran\u00e7ais dans cette communaut\u00e9 \u00e9loign\u00e9e du Nord.","twitter_site":"@CTFFCE","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.ctf-fce.ca\/fr\/journal-education-publique\/vivre-en-francais-en-terre-inuite\/","url":"https:\/\/www.ctf-fce.ca\/fr\/journal-education-publique\/vivre-en-francais-en-terre-inuite\/","name":"Vivre en fran\u00e7ais en terre inuite","isPartOf":{"@id":"https:\/\/www.ctf-fce.ca\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.ctf-fce.ca\/fr\/journal-education-publique\/vivre-en-francais-en-terre-inuite\/#primaryimage"},"image":{"@id":"https:\/\/www.ctf-fce.ca\/fr\/journal-education-publique\/vivre-en-francais-en-terre-inuite\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ctf-fce.ca\/wp-content\/uploads\/2020\/02\/article5.jpg","datePublished":"2016-06-20T04:00:00+00:00","description":"D\u00e9couvrez comment une \u00e9cole de langue fran\u00e7aise au c\u0153ur d\u2019Iqaluit aide \u00e0 pr\u00e9server la vitalit\u00e9 du fran\u00e7ais dans cette communaut\u00e9 \u00e9loign\u00e9e du Nord.","breadcrumb":{"@id":"https:\/\/www.ctf-fce.ca\/fr\/journal-education-publique\/vivre-en-francais-en-terre-inuite\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ctf-fce.ca\/fr\/journal-education-publique\/vivre-en-francais-en-terre-inuite\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.ctf-fce.ca\/fr\/journal-education-publique\/vivre-en-francais-en-terre-inuite\/#primaryimage","url":"https:\/\/www.ctf-fce.ca\/wp-content\/uploads\/2020\/02\/article5.jpg","contentUrl":"https:\/\/www.ctf-fce.ca\/wp-content\/uploads\/2020\/02\/article5.jpg","width":800,"height":500,"caption":"Les participantes et participants du Projet outre-mer de&nbsp;1967 s\u2019appr\u00eatant \u00e0 prendre l\u2019avion vers leur pays d\u2019affectation."},{"@type":"BreadcrumbList","@id":"https:\/\/www.ctf-fce.ca\/fr\/journal-education-publique\/vivre-en-francais-en-terre-inuite\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.ctf-fce.ca\/fr\/home\/"},{"@type":"ListItem","position":2,"name":"Journal de l\u2019\u00e9ducation publique","item":"https:\/\/www.ctf-fce.ca\/fr\/journal-education-publique\/"},{"@type":"ListItem","position":3,"name":"Vivre en fran\u00e7ais en terre inuite"}]},{"@type":"WebSite","@id":"https:\/\/www.ctf-fce.ca\/fr\/#website","url":"https:\/\/www.ctf-fce.ca\/fr\/","name":"CTF-FCE","description":"","publisher":{"@id":"https:\/\/www.ctf-fce.ca\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ctf-fce.ca\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.ctf-fce.ca\/fr\/#organization","name":"CTF-FCE","url":"https:\/\/www.ctf-fce.ca\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.ctf-fce.ca\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.ctf-fce.ca\/wp-content\/uploads\/2020\/01\/ctf-fce-logo@2x.png","contentUrl":"https:\/\/www.ctf-fce.ca\/wp-content\/uploads\/2020\/01\/ctf-fce-logo@2x.png","width":485,"height":146,"caption":"CTF-FCE"},"image":{"@id":"https:\/\/www.ctf-fce.ca\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/CTF.FCE\/","https:\/\/x.com\/CTFFCE","https:\/\/www.instagram.com\/ctffce\/","https:\/\/www.linkedin.com\/company\/canadian-teachers'\u200b-federation---f\u00e9d.-canadienne-des-enseignantes-et-des-enseignants\/","https:\/\/www.youtube.com\/user\/canadianteachers"]}]}},"featured_img":"https:\/\/www.ctf-fce.ca\/wp-content\/uploads\/2020\/02\/article5.jpg","coauthors":[],"author_meta":{"author_link":"https:\/\/www.ctf-fce.ca\/fr\/author\/contactkeshocommunications-ca\/","display_name":"contact@keshocommunications.ca"},"relative_dates":{"created":"Publi\u00e9 10 ans il y a","modified":"Mis \u00e0 jour 10 ans il y a"},"absolute_dates":{"created":"Publi\u00e9 le 20 juin 2016","modified":"Mise \u00e0 jour le 20 juin 2016"},"absolute_dates_time":{"created":"Publi\u00e9 le 20 juin 2016 0h00","modified":"Mise \u00e0 jour le 20 juin 2016 0h00"},"featured_img_caption":"Les participantes et participants du Projet outre-mer de&nbsp;1967 s\u2019appr\u00eatant \u00e0 prendre l\u2019avion vers leur pays d\u2019affectation.","tax_additional":{"categories_perspectives_cpt":{"linked":["<a href=\"https:\/\/www.ctf-fce.ca\/fr\/categories\/education-autochtone\/\" class=\"advgb-post-tax-term\">\u00c9ducation autochtone<\/a>","<a href=\"https:\/\/www.ctf-fce.ca\/fr\/categories\/francophonie-fr\/\" class=\"advgb-post-tax-term\">Francophonie<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">\u00c9ducation autochtone<\/span>","<span class=\"advgb-post-tax-term\">Francophonie<\/span>"],"slug":"categories_perspectives_cpt","name":"Cat\u00e9gories"},"authors_perspectives_cpt":{"linked":["<a href=\"https:\/\/www.ctf-fce.ca\/fr\/auteurs\/ronald-boudreau-fr\/\" class=\"advgb-post-tax-term\">Ronald Boudreau<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">Ronald Boudreau<\/span>"],"slug":"authors_perspectives_cpt","name":"Auteures et auteurs"},"translation_priority":{"linked":["<a href=\"https:\/\/www.ctf-fce.ca\/fr\/?taxonomy=translation_priority&#038;term=facultatif\" class=\"advgb-post-tax-term\">Facultatif<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">Facultatif<\/span>"],"slug":"translation_priority","name":"Priorit\u00e9s de traduction"}},"series_order":"","_links":{"self":[{"href":"https:\/\/www.ctf-fce.ca\/fr\/wp-json\/wp\/v2\/perspectives_cpt\/3026","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ctf-fce.ca\/fr\/wp-json\/wp\/v2\/perspectives_cpt"}],"about":[{"href":"https:\/\/www.ctf-fce.ca\/fr\/wp-json\/wp\/v2\/types\/perspectives_cpt"}],"author":[{"embeddable":true,"href":"https:\/\/www.ctf-fce.ca\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ctf-fce.ca\/fr\/wp-json\/wp\/v2\/comments?post=3026"}],"version-history":[{"count":0,"href":"https:\/\/www.ctf-fce.ca\/fr\/wp-json\/wp\/v2\/perspectives_cpt\/3026\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ctf-fce.ca\/fr\/wp-json\/wp\/v2\/media\/1235"}],"wp:attachment":[{"href":"https:\/\/www.ctf-fce.ca\/fr\/wp-json\/wp\/v2\/media?parent=3026"}],"wp:term":[{"taxonomy":"categories_perspectives_cpt","embeddable":true,"href":"https:\/\/www.ctf-fce.ca\/fr\/wp-json\/wp\/v2\/categories_perspectives_cpt?post=3026"},{"taxonomy":"authors_perspectives_cpt","embeddable":true,"href":"https:\/\/www.ctf-fce.ca\/fr\/wp-json\/wp\/v2\/authors_perspectives_cpt?post=3026"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}