{"id":3030,"date":"2016-06-20T00:00:00","date_gmt":"2016-06-20T04:00:00","guid":{"rendered":"http:\/\/184.107.41.70\/~ctffce\/perspectives_cpt\/les-enseignantes-et-enseignants-de-la-colombie-britannique-epousent-le-projet-du-coeur-la-reconciliation-par-leducation\/"},"modified":"2016-06-20T00:00:00","modified_gmt":"2016-06-20T04:00:00","slug":"les-enseignantes-et-enseignants-de-la-colombie-britannique-epousent-le-projet-du-coeur-la-reconciliation-par-leducation","status":"publish","type":"perspectives_cpt","link":"https:\/\/www.ctf-fce.ca\/fr\/journal-education-publique\/les-enseignantes-et-enseignants-de-la-colombie-britannique-epousent-le-projet-du-coeur-la-reconciliation-par-leducation\/","title":{"rendered":"Les enseignantes et enseignants de la Colombie-Britannique \u00e9pousent le Projet du C\u0153ur : La r\u00e9conciliation par l\u2019\u00e9ducation"},"content":{"rendered":"<p>Gladys Chapman avait 12&nbsp;ans le 29&nbsp;avril&nbsp;1931 quand elle est morte \u00e0 l\u2019h\u00f4pital <span lang=\"en\">Royal Inland<\/span> de Kamloops, en Colombie-Britannique. Sur son certificat de d\u00e9c\u00e8s, le m\u00e9decin M.&nbsp;G.&nbsp;Archibald indique que les causes du d\u00e9c\u00e8s sont une \u00ab&nbsp;dilatation aigu\u00eb du c\u0153ur&nbsp;\u00bb et la tuberculose. Elle a mis \u00ab&nbsp;plusieurs jours&nbsp;\u00bb \u00e0 mourir. La petite Gladys est morte toute seule, loin de chez elle, sans personne pour la r\u00e9conforter. <\/p>\n<p>Le plus tragique, c\u2019est que des milliers d\u2019enfants des pensionnats autochtones sont morts dans des conditions semblables. C\u2019est ce que d\u00e9plore la Commission de v\u00e9rit\u00e9 et r\u00e9conciliation du Canada dans un rapport m\u00e9morable o\u00f9 elle qualifie le traitement que le Canada a r\u00e9serv\u00e9 aux Autochtones de \u00ab&nbsp;g\u00e9nocide culturel&nbsp;\u00bb.<\/p>\n<p>Aujourd\u2019hui, gr\u00e2ce au courage des survivantes et survivants, la v\u00e9rit\u00e9 \u00e9clate enfin au grand jour dans les \u00e9coles et les communaut\u00e9s du pays. Enfin, le voile est lev\u00e9 sur les injustices, et la d\u00e9mocratie canadienne est l\u00e0 pour emp\u00eacher le d\u00e9ni. \u00ab&nbsp;En cette \u00e9poque marquante de l\u2019histoire, les enseignantes et enseignants de la Colombie-Britannique r\u00e9pondent aux 94&nbsp;appels \u00e0 l\u2019action que la Commission a lanc\u00e9s&nbsp;\u00bb, affirme le pr\u00e9sident de la F\u00e9d\u00e9ration des enseignantes et enseignants de la Colombie-Britannique (FECB), Jim&nbsp;Iker. <\/p>\n<div style=\"float: right; width: 48%; min-width:275px; padding-left:12px;\">\n<p style=\"text-align:center\"><img decoding=\"async\" style=\"max-width:100%;height:auto;\" src=\"http:\/\/perspectives.ctf-fce.ca\/Documents\/Articles\/Issue22\/Graphics\/article-10b.jpg\" alt=\"Jeune fille pointant \u00e0 un canot de c\u00e8dre d\u00e9cor\u00e9 de petits carreaux en bois.\" \/><\/p>\n<\/div>\n<div clear=\"both\"><\/div>\n<p>Dans le cadre du Projet du C\u0153ur, les membres de la FECB, dans plus de 500&nbsp;\u00e9coles, ont invit\u00e9 des survivantes et survivants des pensionnats \u00e0 venir raconter leur histoire aux \u00e9l\u00e8ves. Ceux-ci ont d\u00e9cor\u00e9 de petites tuiles de bois, dont des milliers ont ensuite servi \u00e0 composer une mosa\u00efque pour orner un canot en thuya. Le canot comm\u00e9moratif a \u00e9t\u00e9 expos\u00e9 une premi\u00e8re fois au centre culturel U\u2019mista, \u00e0 <span lang=\"en\">Alert&nbsp;Bay<\/span>, \u00e0 l\u2019ombre du triste pensionnat d\u00e9cr\u00e9pit <span style=\"white-space:nowrap;\" lang=\"en\">St.&nbsp;Michael\u2019s.<\/span> Au cours de l\u2019\u00e9t\u00e9, il sera envoy\u00e9 au lieu historique du <span style=\"white-space:nowrap;\">Fort-Langley<\/span> puis au <span lang=\"en\">Langley School District<\/span>, o\u00f9 il pourra facilement devenir un but d\u2019excursion scolaire.<\/p>\n<p>Ces histoires de Gladys et du canot sont racont\u00e9es dans le livre, en version imprim\u00e9e et \u00e9lectronique, de la FECB intitul\u00e9 <a href=\"http:\/\/www.bctf.ca\/HiddenHistory\/\"><em lang=\"en\">Project of Heart: Illuminating the Hidden History of Indian Residential Schools in BC<\/em> (en anglais seulement)<\/a>. Ce livre propose des liens vers des documents historiques, des articles, des photos, des vid\u00e9os, des id\u00e9es de le\u00e7on et plus encore. On le met r\u00e9guli\u00e8rement \u00e0 jour, en y ajoutant notamment des liens vers de nouvelles ressources comme le <a href=\"https:\/\/www.youtube.com\/watch?v=V1NQ_tgR_oA\">r\u00e9cent documentaire r\u00e9alis\u00e9 \u00e0 la m\u00e9moire du m\u00e9decin Peter Henderson Bryce (en anglais seulement)<\/a>, sp\u00e9cialiste de la tuberculose, qui a courageusement donn\u00e9 l\u2019alerte au sujet de l\u2019\u00e9tat de sant\u00e9 lamentable des enfants des pensionnats autochtones. <\/p>\n<p>Depuis son lancement en ao\u00fbt&nbsp;2015, le livre a connu un succ\u00e8s tr\u00e8s encourageant. Les quelque 10&nbsp;000&nbsp;exemplaires imprim\u00e9s se sont envol\u00e9s comme des petits pains, achet\u00e9s par des d\u00e9l\u00e9gu\u00e9es et d\u00e9l\u00e9gu\u00e9s syndicaux de la FECB, des facult\u00e9s d\u2019\u00e9ducation, des membres du corps enseignant eux-m\u00eames, des groupes autochtones et bien d\u2019autres. Une version fran\u00e7aise existe aussi sous le nom <em>Projet du C\u0153ur<\/em> et les ressources qui l\u2019accompagnent sont en cours de traduction. Plus de 30&nbsp;000&nbsp;lecteurs et lectrices de dix pays diff\u00e9rents ont consult\u00e9 la version en ligne. D\u2019autres syndicats de l\u2019enseignement, des syndicats du domaine de la sant\u00e9 et la <span lang=\"en\">British Columbia Federation of Labour<\/span> ont voulu en savoir plus. Le juge en chef de la Cour provinciale de la Colombie-Britannique a m\u00eame command\u00e9 un exemplaire du livre pour chacune et chacun des juges. Et la <span lang=\"en\">Canadian Association of Labour Media<\/span> a r\u00e9cemment salu\u00e9 le projet en lui d\u00e9cernant son prix <span style=\"white-space:nowrap;\" lang=\"en\">Breaking Barriers<\/span>.<\/p>\n<p>Toutes ces r\u00e9actions montrent \u00e0 quel point les Canadiennes et Canadiens sont nombreux \u00e0 vouloir apprendre notre vraie histoire et m\u00eame ses chapitres les plus sombres. Et les enseignantes et enseignants veulent int\u00e9grer du contenu autochtone dans les programmes d\u2019\u00e9tudes, mais ils ont besoin d\u2019aide pour enseigner l\u2019histoire et la culture autochtones avec int\u00e9grit\u00e9 et confiance. Ils ont beaucoup \u00e0 apprendre et doivent pour cela faire un voyage dans le temps, mais aussi au plus profond de leur c\u0153ur.<\/p>\n<p>Paulette Regan, directrice de la Recherche \u00e0 la Commission de v\u00e9rit\u00e9 et r\u00e9conciliation du Canada, pose la question suivante, une question importante pour toutes les Canadiennes et tous les Canadiens, mais peut-\u00eatre plus encore pour celles et ceux qui enseignent&nbsp;: <\/p>\n<p>[Traduction] \u00ab&nbsp;Comment pouvons-nous, nous, les non-Autochtones, arriver \u00e0 nommer puis \u00e0 transformer le colon \u2014 pour ne pas dire le colonisateur \u2014 en nous et pas seulement dans nos mots, mais aussi dans nos actions, tandis que nous devons aujourd\u2019hui faire face \u00e0 l\u2019histoire de colonisation, de violence, de racisme et d\u2019injustice dont t\u00e9moigne l\u2019h\u00e9ritage des pensionnats autochtones?&nbsp;\u00bb<\/p>\n<p><img decoding=\"async\" style=\"max-width:100%;height:auto;\" src=\"http:\/\/perspectives.ctf-fce.ca\/Documents\/Articles\/Issue22\/Graphics\/article-10c.jpg\" alt=\"Un groupe de femmes se tenant derri\u00e8re uncanot de c\u00e8dre d\u00e9cor\u00e9 de petits carreaux en bois.\" \/><\/p>\n<h2>Ateliers connexes offerts (en anglais) par la FECB au personnel enseignant<\/h2>\n<ul>\n<li> Histoire et culture autochtones, parties&nbsp;1 et&nbsp;2<\/li>\n<li> Cr\u00e9er des \u00e9coles sans racisme pour les \u00e9l\u00e8ves autochtones<\/li>\n<li>D\u00e9construire les mythes<\/li>\n<li>Explorer les relations entre les Autochtones et les non-Autochtones&nbsp;: l\u2019exercice de la couverture de la Colombie-Britannique<\/li>\n<li>Les points de vue autochtones<\/li>\n<li>Int\u00e9grer du contenu autochtone, de la maternelle \u00e0 la <span style=\"white-space:nowrap\">7<sup>e<\/sup> ann\u00e9e<\/span> <\/li>\n<li> L\u2019h\u00e9ritage des pensionnats autochtones <\/li>\n<li> Travailler avec les jeunes Autochtones <\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Dans le cadre du Projet<br \/>\ndu C\u0153ur, les membres de la FECB, dans plus de 500&nbsp;\u00e9coles, ont invit\u00e9 des<br \/>\nsurvivantes et survivants des pensionnats \u00e0 venir raconter leur histoire aux<br \/>\n\u00e9l\u00e8ves.<\/p>\n","protected":false},"author":1,"featured_media":1243,"menu_order":0,"comment_status":"closed","ping_status":"open","template":"","format":"standard","meta":{"_acf_changed":false,"advgb_blocks_editor_width":"","advgb_blocks_columns_visual_guide":"","footnotes":""},"categories_perspectives_cpt":[504,497],"authors_perspectives_cpt":[417],"class_list":["post-3030","perspectives_cpt","type-perspectives_cpt","status-publish","format-standard","has-post-thumbnail","hentry","categories_perspectives_cpt-education-autochtone","categories_perspectives_cpt-ressources-pedagogiques","authors_perspectives_cpt-nancy-knickerbocker-fr"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Les enseignantes et enseignants de la Colombie-Britannique \u00e9pousent le Projet du C\u0153ur : La r\u00e9conciliation par l\u2019\u00e9ducation<\/title>\n<meta name=\"description\" content=\"Dans le cadre du Projet du C\u0153ur, les membres de la FECB, dans plus de 500&nbsp;\u00e9coles, ont invit\u00e9 des survivantes et survivants des pensionnats \u00e0 venir raconter leur histoire aux \u00e9l\u00e8ves.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ctf-fce.ca\/fr\/journal-education-publique\/les-enseignantes-et-enseignants-de-la-colombie-britannique-epousent-le-projet-du-coeur-la-reconciliation-par-leducation\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Les enseignantes et enseignants de la Colombie-Britannique \u00e9pousent le Projet du C\u0153ur : La r\u00e9conciliation par l\u2019\u00e9ducation\" \/>\n<meta property=\"og:description\" content=\"Dans le cadre du Projet du C\u0153ur, les membres de la FECB, dans plus de 500&nbsp;\u00e9coles, ont invit\u00e9 des survivantes et survivants des pensionnats \u00e0 venir raconter leur histoire aux \u00e9l\u00e8ves.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ctf-fce.ca\/fr\/journal-education-publique\/les-enseignantes-et-enseignants-de-la-colombie-britannique-epousent-le-projet-du-coeur-la-reconciliation-par-leducation\/\" \/>\n<meta property=\"og:site_name\" content=\"CTF-FCE\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/CTF.FCE\/\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ctf-fce.ca\/wp-content\/uploads\/2020\/02\/article10.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Les enseignantes et enseignants de la Colombie-Britannique \u00e9pousent le Projet du C\u0153ur : La r\u00e9conciliation par l\u2019\u00e9ducation\" \/>\n<meta name=\"twitter:description\" content=\"Dans le cadre du Projet du C\u0153ur, les membres de la FECB, dans plus de 500&nbsp;\u00e9coles, ont invit\u00e9 des survivantes et survivants des pensionnats \u00e0 venir raconter leur histoire aux \u00e9l\u00e8ves.\" \/>\n<meta name=\"twitter:site\" content=\"@CTFFCE\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.ctf-fce.ca\\\/fr\\\/journal-education-publique\\\/les-enseignantes-et-enseignants-de-la-colombie-britannique-epousent-le-projet-du-coeur-la-reconciliation-par-leducation\\\/\",\"url\":\"https:\\\/\\\/www.ctf-fce.ca\\\/fr\\\/journal-education-publique\\\/les-enseignantes-et-enseignants-de-la-colombie-britannique-epousent-le-projet-du-coeur-la-reconciliation-par-leducation\\\/\",\"name\":\"Les enseignantes et enseignants de la Colombie-Britannique \u00e9pousent le Projet du C\u0153ur : La r\u00e9conciliation par l\u2019\u00e9ducation\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ctf-fce.ca\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.ctf-fce.ca\\\/fr\\\/journal-education-publique\\\/les-enseignantes-et-enseignants-de-la-colombie-britannique-epousent-le-projet-du-coeur-la-reconciliation-par-leducation\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ctf-fce.ca\\\/fr\\\/journal-education-publique\\\/les-enseignantes-et-enseignants-de-la-colombie-britannique-epousent-le-projet-du-coeur-la-reconciliation-par-leducation\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.ctf-fce.ca\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/article10.jpg\",\"datePublished\":\"2016-06-20T04:00:00+00:00\",\"description\":\"Dans le cadre du Projet du C\u0153ur, les membres de la FECB, dans plus de 500&nbsp;\u00e9coles, ont invit\u00e9 des survivantes et survivants des pensionnats \u00e0 venir raconter leur histoire aux \u00e9l\u00e8ves.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.ctf-fce.ca\\\/fr\\\/journal-education-publique\\\/les-enseignantes-et-enseignants-de-la-colombie-britannique-epousent-le-projet-du-coeur-la-reconciliation-par-leducation\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.ctf-fce.ca\\\/fr\\\/journal-education-publique\\\/les-enseignantes-et-enseignants-de-la-colombie-britannique-epousent-le-projet-du-coeur-la-reconciliation-par-leducation\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.ctf-fce.ca\\\/fr\\\/journal-education-publique\\\/les-enseignantes-et-enseignants-de-la-colombie-britannique-epousent-le-projet-du-coeur-la-reconciliation-par-leducation\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.ctf-fce.ca\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/article10.jpg\",\"contentUrl\":\"https:\\\/\\\/www.ctf-fce.ca\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/article10.jpg\",\"width\":800,\"height\":500,\"caption\":\"Les enseignantes et enseignants de la Colombie-Britannique \u00e9pousent le Projet du C\u0153ur : La r\u00e9conciliation par l\u2019\u00e9ducation\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.ctf-fce.ca\\\/fr\\\/journal-education-publique\\\/les-enseignantes-et-enseignants-de-la-colombie-britannique-epousent-le-projet-du-coeur-la-reconciliation-par-leducation\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.ctf-fce.ca\\\/fr\\\/home\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Journal de l\u2019\u00e9ducation publique\",\"item\":\"https:\\\/\\\/www.ctf-fce.ca\\\/fr\\\/journal-education-publique\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Les enseignantes et enseignants de la Colombie-Britannique \u00e9pousent le Projet du C\u0153ur : La r\u00e9conciliation par l\u2019\u00e9ducation\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.ctf-fce.ca\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.ctf-fce.ca\\\/fr\\\/\",\"name\":\"CTF-FCE\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.ctf-fce.ca\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.ctf-fce.ca\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.ctf-fce.ca\\\/fr\\\/#organization\",\"name\":\"CTF-FCE\",\"url\":\"https:\\\/\\\/www.ctf-fce.ca\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.ctf-fce.ca\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.ctf-fce.ca\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/ctf-fce-logo@2x.png\",\"contentUrl\":\"https:\\\/\\\/www.ctf-fce.ca\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/ctf-fce-logo@2x.png\",\"width\":485,\"height\":146,\"caption\":\"CTF-FCE\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ctf-fce.ca\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/CTF.FCE\\\/\",\"https:\\\/\\\/x.com\\\/CTFFCE\",\"https:\\\/\\\/www.instagram.com\\\/ctffce\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/canadian-teachers'\u200b-federation---f\u00e9d.-canadienne-des-enseignantes-et-des-enseignants\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/canadianteachers\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Les enseignantes et enseignants de la Colombie-Britannique \u00e9pousent le Projet du C\u0153ur : La r\u00e9conciliation par l\u2019\u00e9ducation","description":"Dans le cadre du Projet du C\u0153ur, les membres de la FECB, dans plus de 500&nbsp;\u00e9coles, ont invit\u00e9 des survivantes et survivants des pensionnats \u00e0 venir raconter leur histoire aux \u00e9l\u00e8ves.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ctf-fce.ca\/fr\/journal-education-publique\/les-enseignantes-et-enseignants-de-la-colombie-britannique-epousent-le-projet-du-coeur-la-reconciliation-par-leducation\/","og_locale":"fr_FR","og_type":"article","og_title":"Les enseignantes et enseignants de la Colombie-Britannique \u00e9pousent le Projet du C\u0153ur : La r\u00e9conciliation par l\u2019\u00e9ducation","og_description":"Dans le cadre du Projet du C\u0153ur, les membres de la FECB, dans plus de 500&nbsp;\u00e9coles, ont invit\u00e9 des survivantes et survivants des pensionnats \u00e0 venir raconter leur histoire aux \u00e9l\u00e8ves.","og_url":"https:\/\/www.ctf-fce.ca\/fr\/journal-education-publique\/les-enseignantes-et-enseignants-de-la-colombie-britannique-epousent-le-projet-du-coeur-la-reconciliation-par-leducation\/","og_site_name":"CTF-FCE","article_publisher":"https:\/\/www.facebook.com\/CTF.FCE\/","og_image":[{"width":800,"height":500,"url":"https:\/\/www.ctf-fce.ca\/wp-content\/uploads\/2020\/02\/article10.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_title":"Les enseignantes et enseignants de la Colombie-Britannique \u00e9pousent le Projet du C\u0153ur : La r\u00e9conciliation par l\u2019\u00e9ducation","twitter_description":"Dans le cadre du Projet du C\u0153ur, les membres de la FECB, dans plus de 500&nbsp;\u00e9coles, ont invit\u00e9 des survivantes et survivants des pensionnats \u00e0 venir raconter leur histoire aux \u00e9l\u00e8ves.","twitter_site":"@CTFFCE","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.ctf-fce.ca\/fr\/journal-education-publique\/les-enseignantes-et-enseignants-de-la-colombie-britannique-epousent-le-projet-du-coeur-la-reconciliation-par-leducation\/","url":"https:\/\/www.ctf-fce.ca\/fr\/journal-education-publique\/les-enseignantes-et-enseignants-de-la-colombie-britannique-epousent-le-projet-du-coeur-la-reconciliation-par-leducation\/","name":"Les enseignantes et enseignants de la Colombie-Britannique \u00e9pousent le Projet du C\u0153ur : La r\u00e9conciliation par l\u2019\u00e9ducation","isPartOf":{"@id":"https:\/\/www.ctf-fce.ca\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.ctf-fce.ca\/fr\/journal-education-publique\/les-enseignantes-et-enseignants-de-la-colombie-britannique-epousent-le-projet-du-coeur-la-reconciliation-par-leducation\/#primaryimage"},"image":{"@id":"https:\/\/www.ctf-fce.ca\/fr\/journal-education-publique\/les-enseignantes-et-enseignants-de-la-colombie-britannique-epousent-le-projet-du-coeur-la-reconciliation-par-leducation\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ctf-fce.ca\/wp-content\/uploads\/2020\/02\/article10.jpg","datePublished":"2016-06-20T04:00:00+00:00","description":"Dans le cadre du Projet du C\u0153ur, les membres de la FECB, dans plus de 500&nbsp;\u00e9coles, ont invit\u00e9 des survivantes et survivants des pensionnats \u00e0 venir raconter leur histoire aux \u00e9l\u00e8ves.","breadcrumb":{"@id":"https:\/\/www.ctf-fce.ca\/fr\/journal-education-publique\/les-enseignantes-et-enseignants-de-la-colombie-britannique-epousent-le-projet-du-coeur-la-reconciliation-par-leducation\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ctf-fce.ca\/fr\/journal-education-publique\/les-enseignantes-et-enseignants-de-la-colombie-britannique-epousent-le-projet-du-coeur-la-reconciliation-par-leducation\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.ctf-fce.ca\/fr\/journal-education-publique\/les-enseignantes-et-enseignants-de-la-colombie-britannique-epousent-le-projet-du-coeur-la-reconciliation-par-leducation\/#primaryimage","url":"https:\/\/www.ctf-fce.ca\/wp-content\/uploads\/2020\/02\/article10.jpg","contentUrl":"https:\/\/www.ctf-fce.ca\/wp-content\/uploads\/2020\/02\/article10.jpg","width":800,"height":500,"caption":"Les enseignantes et enseignants de la Colombie-Britannique \u00e9pousent le Projet du C\u0153ur : La r\u00e9conciliation par l\u2019\u00e9ducation"},{"@type":"BreadcrumbList","@id":"https:\/\/www.ctf-fce.ca\/fr\/journal-education-publique\/les-enseignantes-et-enseignants-de-la-colombie-britannique-epousent-le-projet-du-coeur-la-reconciliation-par-leducation\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.ctf-fce.ca\/fr\/home\/"},{"@type":"ListItem","position":2,"name":"Journal de l\u2019\u00e9ducation publique","item":"https:\/\/www.ctf-fce.ca\/fr\/journal-education-publique\/"},{"@type":"ListItem","position":3,"name":"Les enseignantes et enseignants de la Colombie-Britannique \u00e9pousent le Projet du C\u0153ur : La r\u00e9conciliation par l\u2019\u00e9ducation"}]},{"@type":"WebSite","@id":"https:\/\/www.ctf-fce.ca\/fr\/#website","url":"https:\/\/www.ctf-fce.ca\/fr\/","name":"CTF-FCE","description":"","publisher":{"@id":"https:\/\/www.ctf-fce.ca\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ctf-fce.ca\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.ctf-fce.ca\/fr\/#organization","name":"CTF-FCE","url":"https:\/\/www.ctf-fce.ca\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.ctf-fce.ca\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.ctf-fce.ca\/wp-content\/uploads\/2020\/01\/ctf-fce-logo@2x.png","contentUrl":"https:\/\/www.ctf-fce.ca\/wp-content\/uploads\/2020\/01\/ctf-fce-logo@2x.png","width":485,"height":146,"caption":"CTF-FCE"},"image":{"@id":"https:\/\/www.ctf-fce.ca\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/CTF.FCE\/","https:\/\/x.com\/CTFFCE","https:\/\/www.instagram.com\/ctffce\/","https:\/\/www.linkedin.com\/company\/canadian-teachers'\u200b-federation---f\u00e9d.-canadienne-des-enseignantes-et-des-enseignants\/","https:\/\/www.youtube.com\/user\/canadianteachers"]}]}},"featured_img":"https:\/\/www.ctf-fce.ca\/wp-content\/uploads\/2020\/02\/article10.jpg","coauthors":[],"author_meta":{"author_link":"https:\/\/www.ctf-fce.ca\/fr\/author\/contactkeshocommunications-ca\/","display_name":"contact@keshocommunications.ca"},"relative_dates":{"created":"Publi\u00e9 10 ans il y a","modified":"Mis \u00e0 jour 10 ans il y a"},"absolute_dates":{"created":"Publi\u00e9 le 20 juin 2016","modified":"Mise \u00e0 jour le 20 juin 2016"},"absolute_dates_time":{"created":"Publi\u00e9 le 20 juin 2016 0h00","modified":"Mise \u00e0 jour le 20 juin 2016 0h00"},"featured_img_caption":"","tax_additional":{"categories_perspectives_cpt":{"linked":["<a href=\"https:\/\/www.ctf-fce.ca\/fr\/categories\/education-autochtone\/\" class=\"advgb-post-tax-term\">\u00c9ducation autochtone<\/a>","<a href=\"https:\/\/www.ctf-fce.ca\/fr\/categories\/ressources-pedagogiques\/\" class=\"advgb-post-tax-term\">Ressources p\u00e9dagogiques<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">\u00c9ducation autochtone<\/span>","<span class=\"advgb-post-tax-term\">Ressources p\u00e9dagogiques<\/span>"],"slug":"categories_perspectives_cpt","name":"Cat\u00e9gories"},"authors_perspectives_cpt":{"linked":["<a href=\"https:\/\/www.ctf-fce.ca\/fr\/auteurs\/nancy-knickerbocker-fr\/\" class=\"advgb-post-tax-term\">Nancy Knickerbocker<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">Nancy Knickerbocker<\/span>"],"slug":"authors_perspectives_cpt","name":"Auteures et auteurs"},"translation_priority":{"linked":["<a href=\"https:\/\/www.ctf-fce.ca\/fr\/?taxonomy=translation_priority&#038;term=facultatif\" class=\"advgb-post-tax-term\">Facultatif<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">Facultatif<\/span>"],"slug":"translation_priority","name":"Priorit\u00e9s de traduction"}},"series_order":"","_links":{"self":[{"href":"https:\/\/www.ctf-fce.ca\/fr\/wp-json\/wp\/v2\/perspectives_cpt\/3030","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ctf-fce.ca\/fr\/wp-json\/wp\/v2\/perspectives_cpt"}],"about":[{"href":"https:\/\/www.ctf-fce.ca\/fr\/wp-json\/wp\/v2\/types\/perspectives_cpt"}],"author":[{"embeddable":true,"href":"https:\/\/www.ctf-fce.ca\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ctf-fce.ca\/fr\/wp-json\/wp\/v2\/comments?post=3030"}],"version-history":[{"count":0,"href":"https:\/\/www.ctf-fce.ca\/fr\/wp-json\/wp\/v2\/perspectives_cpt\/3030\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ctf-fce.ca\/fr\/wp-json\/wp\/v2\/media\/1243"}],"wp:attachment":[{"href":"https:\/\/www.ctf-fce.ca\/fr\/wp-json\/wp\/v2\/media?parent=3030"}],"wp:term":[{"taxonomy":"categories_perspectives_cpt","embeddable":true,"href":"https:\/\/www.ctf-fce.ca\/fr\/wp-json\/wp\/v2\/categories_perspectives_cpt?post=3030"},{"taxonomy":"authors_perspectives_cpt","embeddable":true,"href":"https:\/\/www.ctf-fce.ca\/fr\/wp-json\/wp\/v2\/authors_perspectives_cpt?post=3030"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}