{"id":3079,"date":"2018-03-23T00:00:00","date_gmt":"2018-03-23T04:00:00","guid":{"rendered":"http:\/\/184.107.41.70\/~ctffce\/perspectives_cpt\/a-la-defense-du-principe-de-lutilisation-equitable-par-le-personnel-enseignant\/"},"modified":"2020-03-09T21:55:44","modified_gmt":"2020-03-10T01:55:44","slug":"a-la-defense-du-principe-de-lutilisation-equitable-par-le-personnel-enseignant","status":"publish","type":"perspectives_cpt","link":"https:\/\/www.ctf-fce.ca\/fr\/journal-education-publique\/a-la-defense-du-principe-de-lutilisation-equitable-par-le-personnel-enseignant\/","title":{"rendered":"\u00c0 la d\u00e9fense du principe de l\u2019utilisation \u00e9quitable par le personnel enseignant"},"content":{"rendered":"\n<p><br>\n<br>\n<br>\n<meta charset=\"utf-8\"><br>\n<title>Untitled Document<\/title><br>\n<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Dans leur r\u00e9vision de la <em>Loi sur le droit d\u2019auteur<\/em>, les d\u00e9put\u00e9es et d\u00e9put\u00e9s f\u00e9d\u00e9raux se pencheront sur l\u2019acc\u00e8s aux  ressources p\u00e9dagogiques<\/h3>\n\n\n\n<p>La <em>Loi sur le droit d\u2019auteur<\/em> du Canada  comporte une disposition qui donne aux enseignantes et enseignants acc\u00e8s \u00e0 une  vaste gamme de ressources pour pr\u00e9parer leurs le\u00e7ons. Il s\u2019agit de la disposition  relative \u00e0 l\u2019utilisation \u00e9quitable. Cette disposition d\u00e9coule d\u2019une d\u00e9cision de la Cour  supr\u00eame du Canada qui a interpr\u00e9t\u00e9 la mani\u00e8re dont l\u2019utilisation \u00e9quitable s\u2019applique  en salle de classe. La Cour supr\u00eame a d\u00e9cid\u00e9 qu\u2019il \u00e9tait \u00e9quitable, pour les  enseignantes et enseignants, de reproduire de courts extraits de ressources  prot\u00e9g\u00e9es par le droit d\u2019auteur, par exemple des livres, des films, des \u00e9missions  de t\u00e9l\u00e9vision et des \u0153uvres musicales et artistiques.<\/p>\n\n\n\n<p>La  d\u00e9cision de la Cour supr\u00eame ainsi que les changements l\u00e9gislatifs apport\u00e9s \u00e0 la <em>Loi sur le droit d\u2019auteur <\/em>en 2012 ont  procur\u00e9 de nombreux avantages au personnel enseignant et aux \u00e9l\u00e8ves, et grandement  favoris\u00e9 le processus d\u2019apprentissage en classe. Par exemple, et c\u2019est peut-\u00eatre l\u00e0 le plus  grand avantage, les enseignantes et enseignants peuvent maintenant reproduire  de courts extraits d\u2019\u0153uvres prot\u00e9g\u00e9es par le droit d\u2019auteur en vertu de la  disposition relative \u00e0 l\u2019utilisation \u00e9quitable pour enrichir leur mat\u00e9riel  p\u00e9dagogique. L\u2019utilisation \u00e9quitable ne veut pas dire qu\u2019une  enseignante ou un enseignant peut utiliser une \u0153uvre prot\u00e9g\u00e9e de fa\u00e7on  illimit\u00e9e sans la permission n\u00e9cessaire ou le paiement de redevances. Il s\u2019agit plut\u00f4t de permettre au personnel enseignant d\u2019utiliser de  \u00ab&nbsp;courts extraits&nbsp;\u00bb \u00e0 des fins p\u00e9dagogiques. <\/p>\n\n\n\n<p>Afin de  faciliter l\u2019application de la d\u00e9cision de la Cour supr\u00eame, le milieu de l\u2019\u00e9ducation  du Canada a \u00e9labor\u00e9 les <em>Lignes  directrices sur l\u2019utilisation \u00e9quitable<\/em>, que les \u00e9coles, les conseils et  commissions scolaires, et les minist\u00e8res de l\u2019\u00c9ducation ont adopt\u00e9es pour en  faire la politique officielle \u00e0 appliquer. Ces lignes directrices donnent des  indications g\u00e9n\u00e9rales, sans pr\u00e9ciser de limites absolues. Toute reproduction ou communication d\u2019\u0153uvres prot\u00e9g\u00e9es par le droit  d\u2019auteur dans le respect de ces indications serait presque certainement \u00e9quitable  de l\u2019avis des conseillers et conseill\u00e8res juridiques que nous avons consult\u00e9s. Au-del\u00e0 de ces indications, elle pourrait l\u2019\u00eatre ou non. <\/p>\n\n\n\n<div style=\"float: right; width: 50%; border: 1px solid #6fa4c2; padding: 10px; margin-left: 14px; font-size: 0.83em;\">\n<h3 style=\"text-align:center;\">L\u2019outil de d\u00e9cision sur le droit d\u2019auteur <br>\u00e0 l\u2019intention du personnel enseignant : <br>l\u2019<a href=\"http:\/\/www.copyrightdecisiontool.ca\">Arbre d\u00e9cisionnel de l\u2019utilisation \u00e9quitable<\/a><\/h3>\n<p>Il existe un excellent outil en ligne qui aide les enseignantes et enseignants \u00e0 d\u00e9terminer s\u2019ils peuvent ou non utiliser de courts extraits d\u2019\u0153uvres prot\u00e9g\u00e9es par le droit d\u2019auteur pour les \u00e9l\u00e8ves de leur classe.<\/p>\n<p>L\u2019<a href=\"http:\/\/www.copyrightdecisiontool.ca\">Arbre d\u00e9cisionnel de l\u2019utilisation \u00e9quitable<\/a> aide les membres du personnel enseignant \u00e0 d\u00e9cider, en quelques clics, s\u2019ils peuvent reproduire de courts extraits de documents imprim\u00e9s, d\u2019\u0153uvres artistiques ou d\u2019\u0153uvres audiovisuelles en vertu de la disposition relative \u00e0 l\u2019utilisation \u00e9quitable sans avoir \u00e0 obtenir le consentement du titulaire du droit d\u2019auteur.<\/p>\n<p>Alors, la prochaine fois que vous vous demanderez si vous pouvez utiliser tel ou tel document dans votre classe et si vous pouvez le reproduire, consultez l\u2019Arbre d\u00e9cisionnel de l\u2019utilisation \u00e9quitable. Vous aurez la r\u00e9ponse \u00e0 vos questions en quelques secondes! En naviguant dans cet outil convivial, vous vous familiariserez avec la disposition relative \u00e0 l\u2019utilisation \u00e9quitable et apprendrez \u00e0 d\u00e9terminer si vous faites une utilisation \u00e9quitable des \u0153uvres prot\u00e9g\u00e9es par le droit d\u2019auteur.<\/p>\n<p>Vous avez des doutes ou des questions? L\u2019outil de d\u00e9cision sur le droit d\u2019auteur est l\u00e0 pour vous aider.<\/p>\n<p>Visitez le site <a href=\"http:\/\/www.copyrightdecisiontool.ca\">www.CopyrightDecisionTool.ca<\/a> et n\u2019oubliez pas de l\u2019ajouter \u00e0 vos signets!<\/p>\n<p><\/p><\/div>\n\n\n\n<p>Gr\u00e2ce au  principe de l\u2019utilisation \u00e9quitable, la <em>Loi  sur le droit d\u2019auteur<\/em> du Canada favorise l\u2019apprentissage, l\u2019innovation et  la cr\u00e9ation du savoir en donnant au personnel enseignant et aux \u00e9l\u00e8ves le droit  l\u00e9gal d\u2019utiliser \u00e9quitablement les \u0153uvres prot\u00e9g\u00e9es par le droit d\u2019auteur. Elle fournit aux Canadiennes et Canadiens le cadre qui leur permet d\u2019acqu\u00e9rir  les connaissances et les comp\u00e9tences dont ils ont besoin pour soutenir la  concurrence \u00e0 l\u2019\u00e9chelle mondiale. Les enseignantes et enseignants peuvent utiliser les \u0153uvres prot\u00e9g\u00e9es pour enrichir leurs le\u00e7ons et ce, sans craindre d\u2019enfreindre  la <em>Loi<\/em>. Et, surtout,  la disposition relative \u00e0 l\u2019utilisation \u00e9quitable \u00e0 des fins p\u00e9dagogiques place  le personnel enseignant et les \u00e9l\u00e8ves canadiens sur un pied d\u2019\u00e9galit\u00e9 avec  leurs homologues d\u2019autres pays, dont les \u00c9tats-Unis, o\u00f9 la reproduction de  courts extraits est permise sans le paiement de redevances. &nbsp;<\/p>\n\n\n\n<p>Les d\u00e9put\u00e9es  et d\u00e9put\u00e9s f\u00e9d\u00e9raux r\u00e9visent en ce moment la <em>Loi sur le droit d\u2019auteur<\/em>, et la question de l\u2019utilisation  \u00e9quitable \u00e0 des fins p\u00e9dagogiques semble \u00eatre prise pour cible par les maisons  d\u2019\u00e9dition du secteur de l\u2019\u00e9ducation et Access Copyright, l\u2019organisme qui per\u00e7oit  les redevances du secteur de l\u2019\u00e9ducation pour l\u2019utilisation des ressources. Le n\u0153ud du probl\u00e8me est le suivant&nbsp;: aujourd\u2019hui, de nombreuses  utilisations \u00e0 des fins p\u00e9dagogiques d\u2019\u0153uvres prot\u00e9g\u00e9es par le droit d\u2019auteur  n\u2019exigent plus le paiement de redevances, et les maisons d\u2019\u00e9dition attribuent  le d\u00e9clin des ventes de manuels scolaires au recours \u00e0 la disposition relative  \u00e0 l\u2019utilisation \u00e9quitable dans les classes du Canada. Les maisons d\u2019\u00e9dition du secteur de l\u2019\u00e9ducation, les groupes d\u2019auteurs  et auteures, et Access Copyright n\u2019ont pas accept\u00e9 les changements apport\u00e9s \u00e0  la <em>Loi<\/em>. En effet, depuis la d\u00e9cision de 2012 de la Cour  supr\u00eame, ces groupes ont engag\u00e9 quatre contestations judiciaires distinctes  devant les tribunaux et la Commission du droit d\u2019auteur. Ils  ont \u00e9galement fait activement pression sur le gouvernement pour qu\u2019il annule la  d\u00e9cision de la Cour supr\u00eame relative \u00e0 l\u2019utilisation \u00e9quitable et supprime l\u2019\u00e9ducation  comme fin permise de l\u2019utilisation \u00e9quitable. En bref, ils  veulent que la <em>Loi<\/em> oblige de nouveau  les \u00e9coles \u00e0 payer pour la reproduction de courts extraits. <\/p>\n\n\n\n<p>\u00c9tant  donn\u00e9 les efforts acharn\u00e9s que d\u00e9ploient ces groupes de pression, les  enseignantes et enseignants du Canada doivent \u00eatre au courant de la r\u00e9vision de  la <em>Loi sur le droit d\u2019auteur<\/em> et  savoir que les d\u00e9put\u00e9es et d\u00e9put\u00e9s pourraient modifier la disposition relative  \u00e0 l\u2019utilisation \u00e9quitable. Toute modification l\u00e9gislative visant \u00e0 r\u00e9tr\u00e9cir, \u00e0 limiter ou \u00e0 \u00e9liminer les <em>Lignes directrices sur l\u2019utilisation \u00e9quitable<\/em> aurait un effet  n\u00e9faste sur la qualit\u00e9 de l\u2019enseignement et de l\u2019apprentissage au Canada. La F\u00e9d\u00e9ration canadienne des enseignantes et des enseignants  (FCE) et ses organisations Membres travaillent avec d\u2019autres organisations  nationales pour sensibiliser la population aux avantages de l\u2019utilisation \u00e9quitable  et contrer l\u2019information erron\u00e9e provenant du lobby des maisons d\u2019\u00e9dition. Veuillez communiquer avec nous pour obtenir de plus amples renseignements sur la r\u00e9vision de la <em>Loi<\/em> par le  Parlement du Canada.<\/p>\n\n\n\n<p>Les  d\u00e9put\u00e9es et d\u00e9put\u00e9s doivent savoir \u00e0 quel point l\u2019utilisation \u00e9quitable est  importante pour le personnel enseignant. Vous pouvez  participer \u00e0 la campagne d\u2019action politique de la FCE afin de faire valoir  toute l\u2019importance que repr\u00e9sente pour vous l\u2019utilisation \u00e9quitable dans le  cadre de la r\u00e9vision de la <em>Loi sur le  droit d\u2019auteur<\/em> par le Parlement du Canada.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dans le contexte de la r\u00e9vision de la <i>Loi sur le droit d\u2019auteur<\/i> par le Parlement du Canada, un changement l\u00e9gislatif en faveur du lobby des maisons d\u2019\u00e9dition permettrait \u00e0 ces derni\u00e8res de remplir leurs coffres aux d\u00e9pens de l\u2019\u00e9ducation publique.<\/p>\n","protected":false},"author":1,"featured_media":1332,"menu_order":0,"comment_status":"closed","ping_status":"open","template":"","format":"standard","meta":{"_acf_changed":false,"advgb_blocks_editor_width":"","advgb_blocks_columns_visual_guide":"","footnotes":""},"categories_perspectives_cpt":[494,516],"authors_perspectives_cpt":[436],"class_list":["post-3079","perspectives_cpt","type-perspectives_cpt","status-publish","format-standard","has-post-thumbnail","hentry","categories_perspectives_cpt-droit-dauteur","categories_perspectives_cpt-profession-enseignante","authors_perspectives_cpt-chris-george-fr"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u00c0 la d\u00e9fense du principe de l\u2019utilisation \u00e9quitable par le personnel enseignant<\/title>\n<meta name=\"description\" content=\"Dans le contexte de la r\u00e9vision de la Loi sur le droit d\u2019auteur par le Parlement du Canada, un changement l\u00e9gislatif en faveur du lobby des maisons d\u2019\u00e9dition permettrait \u00e0 ces derni\u00e8res de remplir leurs coffres aux d\u00e9pens de l\u2019\u00e9ducation publique.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ctf-fce.ca\/fr\/journal-education-publique\/a-la-defense-du-principe-de-lutilisation-equitable-par-le-personnel-enseignant\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00c0 la d\u00e9fense du principe de l\u2019utilisation \u00e9quitable par le personnel enseignant\" \/>\n<meta property=\"og:description\" content=\"Dans le contexte de la r\u00e9vision de la Loi sur le droit d\u2019auteur par le Parlement du Canada, un changement l\u00e9gislatif en faveur du lobby des maisons d\u2019\u00e9dition permettrait \u00e0 ces derni\u00e8res de remplir leurs coffres aux d\u00e9pens de l\u2019\u00e9ducation publique.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ctf-fce.ca\/fr\/journal-education-publique\/a-la-defense-du-principe-de-lutilisation-equitable-par-le-personnel-enseignant\/\" \/>\n<meta property=\"og:site_name\" content=\"CTF-FCE\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/CTF.FCE\/\" \/>\n<meta property=\"article:modified_time\" content=\"2020-03-10T01:55:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ctf-fce.ca\/wp-content\/uploads\/2020\/02\/Articles-9_800x500.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"\u00c0 la d\u00e9fense du principe de l\u2019utilisation \u00e9quitable par le personnel enseignant\" \/>\n<meta name=\"twitter:description\" content=\"Dans le contexte de la r\u00e9vision de la Loi sur le droit d\u2019auteur par le Parlement du Canada, un changement l\u00e9gislatif en faveur du lobby des maisons d\u2019\u00e9dition permettrait \u00e0 ces derni\u00e8res de remplir leurs coffres aux d\u00e9pens de l\u2019\u00e9ducation publique.\" \/>\n<meta name=\"twitter:site\" content=\"@CTFFCE\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.ctf-fce.ca\\\/fr\\\/journal-education-publique\\\/a-la-defense-du-principe-de-lutilisation-equitable-par-le-personnel-enseignant\\\/\",\"url\":\"https:\\\/\\\/www.ctf-fce.ca\\\/fr\\\/journal-education-publique\\\/a-la-defense-du-principe-de-lutilisation-equitable-par-le-personnel-enseignant\\\/\",\"name\":\"\u00c0 la d\u00e9fense du principe de l\u2019utilisation \u00e9quitable par le personnel enseignant\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ctf-fce.ca\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.ctf-fce.ca\\\/fr\\\/journal-education-publique\\\/a-la-defense-du-principe-de-lutilisation-equitable-par-le-personnel-enseignant\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ctf-fce.ca\\\/fr\\\/journal-education-publique\\\/a-la-defense-du-principe-de-lutilisation-equitable-par-le-personnel-enseignant\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.ctf-fce.ca\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/Articles-9_800x500.png\",\"datePublished\":\"2018-03-23T04:00:00+00:00\",\"dateModified\":\"2020-03-10T01:55:44+00:00\",\"description\":\"Dans le contexte de la r\u00e9vision de la Loi sur le droit d\u2019auteur par le Parlement du Canada, un changement l\u00e9gislatif en faveur du lobby des maisons d\u2019\u00e9dition permettrait \u00e0 ces derni\u00e8res de remplir leurs coffres aux d\u00e9pens de l\u2019\u00e9ducation publique.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.ctf-fce.ca\\\/fr\\\/journal-education-publique\\\/a-la-defense-du-principe-de-lutilisation-equitable-par-le-personnel-enseignant\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.ctf-fce.ca\\\/fr\\\/journal-education-publique\\\/a-la-defense-du-principe-de-lutilisation-equitable-par-le-personnel-enseignant\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.ctf-fce.ca\\\/fr\\\/journal-education-publique\\\/a-la-defense-du-principe-de-lutilisation-equitable-par-le-personnel-enseignant\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.ctf-fce.ca\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/Articles-9_800x500.png\",\"contentUrl\":\"https:\\\/\\\/www.ctf-fce.ca\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/Articles-9_800x500.png\",\"width\":800,\"height\":500,\"caption\":\"\u00c0 la d\u00e9fense du principe de l\u2019utilisation \u00e9quitable par le personnel enseignant\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.ctf-fce.ca\\\/fr\\\/journal-education-publique\\\/a-la-defense-du-principe-de-lutilisation-equitable-par-le-personnel-enseignant\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.ctf-fce.ca\\\/fr\\\/home\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Journal de l\u2019\u00e9ducation publique\",\"item\":\"https:\\\/\\\/www.ctf-fce.ca\\\/fr\\\/journal-education-publique\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"\u00c0 la d\u00e9fense du principe de l\u2019utilisation \u00e9quitable par le personnel enseignant\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.ctf-fce.ca\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.ctf-fce.ca\\\/fr\\\/\",\"name\":\"CTF-FCE\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.ctf-fce.ca\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.ctf-fce.ca\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.ctf-fce.ca\\\/fr\\\/#organization\",\"name\":\"CTF-FCE\",\"url\":\"https:\\\/\\\/www.ctf-fce.ca\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.ctf-fce.ca\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.ctf-fce.ca\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/ctf-fce-logo@2x.png\",\"contentUrl\":\"https:\\\/\\\/www.ctf-fce.ca\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/ctf-fce-logo@2x.png\",\"width\":485,\"height\":146,\"caption\":\"CTF-FCE\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ctf-fce.ca\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/CTF.FCE\\\/\",\"https:\\\/\\\/x.com\\\/CTFFCE\",\"https:\\\/\\\/www.instagram.com\\\/ctffce\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/canadian-teachers'\u200b-federation---f\u00e9d.-canadienne-des-enseignantes-et-des-enseignants\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/canadianteachers\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00c0 la d\u00e9fense du principe de l\u2019utilisation \u00e9quitable par le personnel enseignant","description":"Dans le contexte de la r\u00e9vision de la Loi sur le droit d\u2019auteur par le Parlement du Canada, un changement l\u00e9gislatif en faveur du lobby des maisons d\u2019\u00e9dition permettrait \u00e0 ces derni\u00e8res de remplir leurs coffres aux d\u00e9pens de l\u2019\u00e9ducation publique.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ctf-fce.ca\/fr\/journal-education-publique\/a-la-defense-du-principe-de-lutilisation-equitable-par-le-personnel-enseignant\/","og_locale":"fr_FR","og_type":"article","og_title":"\u00c0 la d\u00e9fense du principe de l\u2019utilisation \u00e9quitable par le personnel enseignant","og_description":"Dans le contexte de la r\u00e9vision de la Loi sur le droit d\u2019auteur par le Parlement du Canada, un changement l\u00e9gislatif en faveur du lobby des maisons d\u2019\u00e9dition permettrait \u00e0 ces derni\u00e8res de remplir leurs coffres aux d\u00e9pens de l\u2019\u00e9ducation publique.","og_url":"https:\/\/www.ctf-fce.ca\/fr\/journal-education-publique\/a-la-defense-du-principe-de-lutilisation-equitable-par-le-personnel-enseignant\/","og_site_name":"CTF-FCE","article_publisher":"https:\/\/www.facebook.com\/CTF.FCE\/","article_modified_time":"2020-03-10T01:55:44+00:00","og_image":[{"width":800,"height":500,"url":"https:\/\/www.ctf-fce.ca\/wp-content\/uploads\/2020\/02\/Articles-9_800x500.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_title":"\u00c0 la d\u00e9fense du principe de l\u2019utilisation \u00e9quitable par le personnel enseignant","twitter_description":"Dans le contexte de la r\u00e9vision de la Loi sur le droit d\u2019auteur par le Parlement du Canada, un changement l\u00e9gislatif en faveur du lobby des maisons d\u2019\u00e9dition permettrait \u00e0 ces derni\u00e8res de remplir leurs coffres aux d\u00e9pens de l\u2019\u00e9ducation publique.","twitter_site":"@CTFFCE","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.ctf-fce.ca\/fr\/journal-education-publique\/a-la-defense-du-principe-de-lutilisation-equitable-par-le-personnel-enseignant\/","url":"https:\/\/www.ctf-fce.ca\/fr\/journal-education-publique\/a-la-defense-du-principe-de-lutilisation-equitable-par-le-personnel-enseignant\/","name":"\u00c0 la d\u00e9fense du principe de l\u2019utilisation \u00e9quitable par le personnel enseignant","isPartOf":{"@id":"https:\/\/www.ctf-fce.ca\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.ctf-fce.ca\/fr\/journal-education-publique\/a-la-defense-du-principe-de-lutilisation-equitable-par-le-personnel-enseignant\/#primaryimage"},"image":{"@id":"https:\/\/www.ctf-fce.ca\/fr\/journal-education-publique\/a-la-defense-du-principe-de-lutilisation-equitable-par-le-personnel-enseignant\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ctf-fce.ca\/wp-content\/uploads\/2020\/02\/Articles-9_800x500.png","datePublished":"2018-03-23T04:00:00+00:00","dateModified":"2020-03-10T01:55:44+00:00","description":"Dans le contexte de la r\u00e9vision de la Loi sur le droit d\u2019auteur par le Parlement du Canada, un changement l\u00e9gislatif en faveur du lobby des maisons d\u2019\u00e9dition permettrait \u00e0 ces derni\u00e8res de remplir leurs coffres aux d\u00e9pens de l\u2019\u00e9ducation publique.","breadcrumb":{"@id":"https:\/\/www.ctf-fce.ca\/fr\/journal-education-publique\/a-la-defense-du-principe-de-lutilisation-equitable-par-le-personnel-enseignant\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ctf-fce.ca\/fr\/journal-education-publique\/a-la-defense-du-principe-de-lutilisation-equitable-par-le-personnel-enseignant\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.ctf-fce.ca\/fr\/journal-education-publique\/a-la-defense-du-principe-de-lutilisation-equitable-par-le-personnel-enseignant\/#primaryimage","url":"https:\/\/www.ctf-fce.ca\/wp-content\/uploads\/2020\/02\/Articles-9_800x500.png","contentUrl":"https:\/\/www.ctf-fce.ca\/wp-content\/uploads\/2020\/02\/Articles-9_800x500.png","width":800,"height":500,"caption":"\u00c0 la d\u00e9fense du principe de l\u2019utilisation \u00e9quitable par le personnel enseignant"},{"@type":"BreadcrumbList","@id":"https:\/\/www.ctf-fce.ca\/fr\/journal-education-publique\/a-la-defense-du-principe-de-lutilisation-equitable-par-le-personnel-enseignant\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.ctf-fce.ca\/fr\/home\/"},{"@type":"ListItem","position":2,"name":"Journal de l\u2019\u00e9ducation publique","item":"https:\/\/www.ctf-fce.ca\/fr\/journal-education-publique\/"},{"@type":"ListItem","position":3,"name":"\u00c0 la d\u00e9fense du principe de l\u2019utilisation \u00e9quitable par le personnel enseignant"}]},{"@type":"WebSite","@id":"https:\/\/www.ctf-fce.ca\/fr\/#website","url":"https:\/\/www.ctf-fce.ca\/fr\/","name":"CTF-FCE","description":"","publisher":{"@id":"https:\/\/www.ctf-fce.ca\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ctf-fce.ca\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.ctf-fce.ca\/fr\/#organization","name":"CTF-FCE","url":"https:\/\/www.ctf-fce.ca\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.ctf-fce.ca\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.ctf-fce.ca\/wp-content\/uploads\/2020\/01\/ctf-fce-logo@2x.png","contentUrl":"https:\/\/www.ctf-fce.ca\/wp-content\/uploads\/2020\/01\/ctf-fce-logo@2x.png","width":485,"height":146,"caption":"CTF-FCE"},"image":{"@id":"https:\/\/www.ctf-fce.ca\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/CTF.FCE\/","https:\/\/x.com\/CTFFCE","https:\/\/www.instagram.com\/ctffce\/","https:\/\/www.linkedin.com\/company\/canadian-teachers'\u200b-federation---f\u00e9d.-canadienne-des-enseignantes-et-des-enseignants\/","https:\/\/www.youtube.com\/user\/canadianteachers"]}]}},"featured_img":"https:\/\/www.ctf-fce.ca\/wp-content\/uploads\/2020\/02\/Articles-9_800x500.png","coauthors":[],"author_meta":{"author_link":"https:\/\/www.ctf-fce.ca\/fr\/author\/contactkeshocommunications-ca\/","display_name":"contact@keshocommunications.ca"},"relative_dates":{"created":"Publi\u00e9 8 ans il y a","modified":"Mis \u00e0 jour 6 ans il y a"},"absolute_dates":{"created":"Publi\u00e9 le 23 mars 2018","modified":"Mise \u00e0 jour le 9 mars 2020"},"absolute_dates_time":{"created":"Publi\u00e9 le 23 mars 2018 0h00","modified":"Mise \u00e0 jour le 9 mars 2020 21h55"},"featured_img_caption":"","tax_additional":{"categories_perspectives_cpt":{"linked":["<a href=\"https:\/\/www.ctf-fce.ca\/fr\/categories\/droit-dauteur\/\" class=\"advgb-post-tax-term\">Droit d\u2019auteur<\/a>","<a href=\"https:\/\/www.ctf-fce.ca\/fr\/categories\/profession-enseignante\/\" class=\"advgb-post-tax-term\">Profession enseignante<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">Droit d\u2019auteur<\/span>","<span class=\"advgb-post-tax-term\">Profession enseignante<\/span>"],"slug":"categories_perspectives_cpt","name":"Cat\u00e9gories"},"authors_perspectives_cpt":{"linked":["<a href=\"https:\/\/www.ctf-fce.ca\/fr\/auteurs\/chris-george-fr\/\" class=\"advgb-post-tax-term\">Chris George<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">Chris George<\/span>"],"slug":"authors_perspectives_cpt","name":"Auteures et auteurs"},"translation_priority":{"linked":["<a href=\"https:\/\/www.ctf-fce.ca\/fr\/?taxonomy=translation_priority&#038;term=facultatif\" class=\"advgb-post-tax-term\">Facultatif<\/a>"],"unlinked":["<span class=\"advgb-post-tax-term\">Facultatif<\/span>"],"slug":"translation_priority","name":"Priorit\u00e9s de traduction"}},"series_order":"","_links":{"self":[{"href":"https:\/\/www.ctf-fce.ca\/fr\/wp-json\/wp\/v2\/perspectives_cpt\/3079","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ctf-fce.ca\/fr\/wp-json\/wp\/v2\/perspectives_cpt"}],"about":[{"href":"https:\/\/www.ctf-fce.ca\/fr\/wp-json\/wp\/v2\/types\/perspectives_cpt"}],"author":[{"embeddable":true,"href":"https:\/\/www.ctf-fce.ca\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ctf-fce.ca\/fr\/wp-json\/wp\/v2\/comments?post=3079"}],"version-history":[{"count":0,"href":"https:\/\/www.ctf-fce.ca\/fr\/wp-json\/wp\/v2\/perspectives_cpt\/3079\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ctf-fce.ca\/fr\/wp-json\/wp\/v2\/media\/1332"}],"wp:attachment":[{"href":"https:\/\/www.ctf-fce.ca\/fr\/wp-json\/wp\/v2\/media?parent=3079"}],"wp:term":[{"taxonomy":"categories_perspectives_cpt","embeddable":true,"href":"https:\/\/www.ctf-fce.ca\/fr\/wp-json\/wp\/v2\/categories_perspectives_cpt?post=3079"},{"taxonomy":"authors_perspectives_cpt","embeddable":true,"href":"https:\/\/www.ctf-fce.ca\/fr\/wp-json\/wp\/v2\/authors_perspectives_cpt?post=3079"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}